{"id":1451,"date":"2026-02-12T04:01:49","date_gmt":"2026-02-12T04:01:49","guid":{"rendered":"https:\/\/hexatrontech.com\/fr\/?post_type=products&#038;p=1451"},"modified":"2026-02-12T04:38:44","modified_gmt":"2026-02-12T04:38:44","slug":"laser-lgp","status":"publish","type":"products","link":"https:\/\/hexatrontech.com\/fr\/our-products\/light-guide-plate-lgp\/laser-lgp\/","title":{"rendered":"Laser LGP"},"content":{"rendered":"\n<div class=\"rounded-2xl wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"mb-8 wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\"><\/div><\/div>\n\n\n\n<div class=\"gap-12 items-start wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<h1 class=\"h1-no-margin-top wp-block-heading\">Laser LGP<\/h1>\n\n\n\n<p class=\"text-xl text-gray-600 mb-8 wp-block-paragraph\">La&nbsp;<strong>Placa de Guidage de Lumi\u00e8re Laser (Laser LGP)<\/strong>&nbsp;est un composant optique de haute pr\u00e9cision con\u00e7u pour offrir un&nbsp;<strong>\u00e9clairage uniforme et \u00e0 haute efficacit\u00e9<\/strong>&nbsp;dans les syst\u00e8mes d&#8217;\u00e9clairage LED. Gr\u00e2ce \u00e0 l&#8217;utilisation de&nbsp;<strong>motifs de points grav\u00e9s au laser<\/strong>, notre Laser LGP permet un contr\u00f4le exceptionnel de l&#8217;extraction de la lumi\u00e8re sur toute la surface, garantissant une uniformit\u00e9 de luminosit\u00e9 sup\u00e9rieure.<\/p>\n\n\n\n<p class=\"text-xl text-gray-600 mb-8 wp-block-paragraph\">Fabriqu\u00e9e \u00e0 partir de&nbsp;<strong>PMMA de qualit\u00e9 optique<\/strong>&nbsp;avec une technologie de traitement laser avanc\u00e9e, la Laser LGP est id\u00e9ale pour les applications n\u00e9cessitant une&nbsp;<strong>diffusion de lumi\u00e8re sur de grandes surfaces<\/strong>, un&nbsp;<strong>flux lumineux \u00e9lev\u00e9<\/strong>&nbsp;et des&nbsp;<strong>formats ultra-plats<\/strong>.<\/p>\n\n\n\n<h3 class=\"text-lg font-semibold text-gray-900 mb-4 wp-block-heading\">Certifications<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/hexatrontech.com\/wp-content\/uploads\/2025\/12\/Frame-5-7-1024x252.jpg\" alt=\"\" class=\"wp-image-2178\"\/><\/figure>\n\n\n\n<div class=\"mt-8 wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-luminous-vivid-orange-background-color has-text-color has-background has-link-color wp-element-button\" href=\"#request-quote\">Demander une fiche technique ou une certification<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<div class=\"space-y-6 wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"rounded-xl shadow-lg overflow-hidden mb-6 wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"is-clickable wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/hexatrontech.com\/wp-content\/uploads\/2019\/07\/hexatron-light-guide-plate-pmma-high-uniformity-1024x683.jpg\" alt=\"Hexatron Light Guide Plate PMMA for high-uniformity LED lighting\" class=\"wp-image-680\"\/><\/figure>\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"rounded-2xl wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"text-3xl font-bold text-gray-900 mb-6 wp-block-heading\">Sp\u00e9cifications Techniques<\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><td><strong>Attribut<\/strong><\/td><td><strong>Valeur \/ Plage<\/strong><\/td><\/tr><\/thead><tbody><tr><td><strong>Mat\u00e9riau<\/strong><\/td><td>PMMA de qualit\u00e9 optique (acrylique)<\/td><\/tr><tr><td><strong>\u00c9paisseur<\/strong><\/td><td>2 mm \u2013 15 mm<\/td><\/tr><tr><td><strong>Taille maximale du panneau<\/strong><\/td><td>Jusqu&#8217;\u00e0 2 000 \u00d7 4 000 mm<\/td><\/tr><tr><td><strong>Traitement de surface<\/strong><\/td><td>Motif de points grav\u00e9s au laser<\/td><\/tr><tr><td><strong>Transmission lumineuse<\/strong><\/td><td>\u2265 92 % (PMMA clair)<\/td><\/tr><tr><td><strong>Contr\u00f4le de la r\u00e9flexion<\/strong><\/td><td>Densit\u00e9 de points laser personnalis\u00e9e<\/td><\/tr><tr><td><strong>R\u00e9sistance aux UV<\/strong><\/td><td>Stabilis\u00e9 aux UV<\/td><\/tr><tr><td><strong>Temp\u00e9rature de service<\/strong><\/td><td>-20\u00b0C \u00e0 +70\u00b0C (selon l&#8217;application)<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"text-3xl font-bold text-gray-900 mb-6 wp-block-heading\">LGP Micro-Patterning Technologies<\/h2>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" src=\"https:\/\/hexatrontech.com\/wp-content\/uploads\/2025\/12\/Screenshot-2026-02-03-at-9.28.36-PM-e1770125382517.png\" alt=\"\" class=\"wp-image-2523 size-full\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><strong>Des plaques de guidage de lumi\u00e8re sur mesure pour chaque application.<\/strong>\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chaque LGP est con\u00e7ue de mani\u00e8re personnalis\u00e9e \u00e0 l&#8217;aide d&#8217;un algorithme propri\u00e9taire. En analysant des variables cl\u00e9s telles que les dimensions du panneau et les points d&#8217;entr\u00e9e de la lumi\u00e8re, nous optimisons la densit\u00e9 des points laser pour obtenir la meilleure uniformit\u00e9 possible.<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Produits Compl\u00e9mentaires<\/h2>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" src=\"https:\/\/hexatrontech.com\/wp-content\/uploads\/2025\/12\/LGP-Bundle-3-1024x597.jpg\" alt=\"\" class=\"wp-image-2543 size-full\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">Les Laser LGP sont g\u00e9n\u00e9ralement associ\u00e9es \u00e0 des\u00a0<strong>feuilles de diffusion frontales<\/strong>\u00a0(opales ou optimis\u00e9es UGR&lt;19). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les\u00a0<strong>feuilles r\u00e9fl\u00e9chissantes arri\u00e8re<\/strong>\u00a0am\u00e9liorent le rendement en redirigeant la lumi\u00e8re \u00e9mise vers l&#8217;arri\u00e8re vers la surface frontale, augmentant ainsi l&#8217;efficacit\u00e9 globale du syst\u00e8me.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous proposons un \u00ab pack optique \u00bb complet pour simplifier votre cha\u00eene d&#8217;approvisionnement et garantir la compatibilit\u00e9 des composants.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Plus d&#8217;informations<\/h2>\n\n\n\n<div class=\"wp-block-create-block-faq-anderson-plugin\"><div class=\"faq-item\"><div class=\"faq-title\"><h4 class=\"faq-item-title-heading\">D\u00e9coupe, Usinage et Fabrication sur Mesure<\/h4><span class=\"faq-icon\">+<\/span><\/div><div class=\"faq-content\">\n<p class=\"wp-block-paragraph\">EChaque&nbsp;<strong>Plaque de Guidage de Lumi\u00e8re (LGP)<\/strong>&nbsp;est enti\u00e8rement personnalisable pour r\u00e9pondre \u00e0 vos exigences sp\u00e9cifiques de conception et d&#8217;assemblage. Une technologie de fabrication de pointe garantit une d\u00e9coupe de pr\u00e9cision, une clart\u00e9 optique et une qualit\u00e9 constante pour toutes les applications.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nos capacit\u00e9s incluent :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"\">D\u00e9coupe, fraisage et per\u00e7age CNC<\/li>\n\n\n\n<li class=\"\">Gravure laser pour les motifs d&#8217;extraction de lumi\u00e8re<\/li>\n\n\n\n<li class=\"\">Finition et polissage des chants pour une haute transparence<\/li>\n\n\n\n<li class=\"\">Usinage \u00e0 tol\u00e9rance \u00e9troite pour un alignement parfait<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Accompagnement pour le d\u00e9veloppement de prototypes et la production de masse avec des performances optiques stables et reproductibles.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-create-block-faq-anderson-plugin\"><div class=\"faq-item\"><div class=\"faq-title\"><h4 class=\"faq-item-title-heading\">Propri\u00e9t\u00e9s et Tol\u00e9rances Typiques du PMMA de Qualit\u00e9 Optique\u00a0<\/h4><span class=\"faq-icon\">+<\/span><\/div><div class=\"faq-content\">\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>Property<\/td><td>Typical Value \/ Tolerance<\/td><\/tr><tr><td>Thickness<\/td><td>\u00b1 0.1 mm (3 to 15mm)<\/td><\/tr><tr><td>Dimensional (length \u00d7 width)<\/td><td>\u00b1 0.3 mm<\/td><\/tr><tr><td>Material clarity \/ defects<\/td><td>No inclusions, bubbles, scratches visible; optical grade<\/td><\/tr><tr><td>Uniformity<\/td><td>\u2265 85% uniformity depending on size; for small size often higher<\/td><\/tr><tr><td>Thermal expansion<\/td><td>~ 7 \u00d7 10\u207b\u2075 \/ \u00b0C<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Laser LGP La&nbsp;Placa de Guidage de Lumi\u00e8re Laser (Laser LGP)&nbsp;est un composant optique de haute pr\u00e9cision con\u00e7u pour offrir un&nbsp;\u00e9clairage uniforme et \u00e0 haute efficacit\u00e9&nbsp;dans les syst\u00e8mes d&#8217;\u00e9clairage LED. Gr\u00e2ce \u00e0 l&#8217;utilisation de&nbsp;motifs de points grav\u00e9s au laser, notre Laser LGP permet un contr\u00f4le exceptionnel de l&#8217;extraction de la lumi\u00e8re sur toute la surface, garantissant [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":1342,"menu_order":1,"template":"","class_list":["post-1451","products","type-products","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/hexatrontech.com\/fr\/wp-json\/wp\/v2\/products\/1451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hexatrontech.com\/fr\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/hexatrontech.com\/fr\/wp-json\/wp\/v2\/types\/products"}],"up":[{"embeddable":true,"href":"https:\/\/hexatrontech.com\/fr\/wp-json\/wp\/v2\/products\/1342"}],"wp:attachment":[{"href":"https:\/\/hexatrontech.com\/fr\/wp-json\/wp\/v2\/media?parent=1451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}